{"id":3,"date":"2025-04-10T11:35:39","date_gmt":"2025-04-10T09:35:39","guid":{"rendered":"https:\/\/www.stoprodent.com\/?page_id=3"},"modified":"2026-04-24T12:34:14","modified_gmt":"2026-04-24T10:34:14","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.stoprodent.com\/ch-de\/privacy-policy\/","title":{"rendered":"Datenschutzbestimmungen"},"content":{"rendered":"<p><em>Letzte Aktualisierung: 24. April 2026<\/em><\/p>\n\n\n\n<p><strong>Artikel 1. Pr\u00e4sentation der Website<\/strong><\/p>\n\n\n\n<p>Den Nutzern der Website wird die Identit\u00e4t der verschiedenen Beteiligten im Zusammenhang mit der Realisierung und dem Follow-up der Website mitgeteilt:<\/p>\n\n\n\n<p>Besitzer : Ferber Enterprises O\u00dc<br>Adresse: Tornim\u00e4e tn 5, 10145, Tallinn, Estland<br>Rechtsform: Gesellschaft mit beschr\u00e4nkter Haftung<br>Estnischer Handelsregisternummer: 17475718<br>Europ\u00e4ische Umsatzsteuer-Identifikationsnummer: EE102979314<br>E-Mail-Adresse: contact@stoprodent.com<br>Gastgeber : OVH SAS, 2 rue Kellermann, Roubaix, 59100, Frankreich<\/p>\n\n\n\n<p><strong>Artikel 2. Allgemeine Bedingungen f\u00fcr die Verwendung<\/strong>&nbsp;<strong>der Website und der angebotenen Dienstleistungen<\/strong><\/p>\n\n\n\n<p>Die Nutzung der Website setzt die uneingeschr\u00e4nkte Zustimmung zu den nachstehend beschriebenen allgemeinen Nutzungsbedingungen voraus. Diese Nutzungsbedingungen k\u00f6nnen jederzeit ge\u00e4ndert oder erg\u00e4nzt werden; die Nutzer der Website werden daher gebeten, sie regelm\u00e4\u00dfig zu konsultieren.<\/p>\n\n\n\n<p>Diese Website ist normalerweise jederzeit f\u00fcr Benutzer zug\u00e4nglich. Eine Unterbrechung aufgrund technischer Wartungsarbeiten kann jedoch vom Website-Betreiber beschlossen werden, der sich dann bem\u00fcht, die Benutzer vor den Terminen und Zeiten des Eingriffs zu informieren.<\/p>\n\n\n\n<p>Die Website wird regelm\u00e4\u00dfig vom Website-Betreiber aktualisiert. Ebenso k\u00f6nnen die rechtlichen Hinweise jederzeit ge\u00e4ndert werden: Sie sind f\u00fcr den Nutzer dennoch bindend, der aufgefordert wird, sie so oft wie m\u00f6glich zu konsultieren, um sich mit ihnen vertraut zu machen.<\/p>\n\n\n\n<p><strong>Artikel 3. Beschreibung der erbrachten Dienstleistungen<\/strong><\/p>\n\n\n\n<p>Ziel der Website ist es, Informationen \u00fcber alle Aktivit\u00e4ten des Unternehmens bereitzustellen.<\/p>\n\n\n\n<p>Der Website-Betreiber ist bestrebt, Informationen auf der Website bereitzustellen, die so genau wie m\u00f6glich sind. Er kann jedoch nicht f\u00fcr Auslassungen, Ungenauigkeiten und M\u00e4ngel bei der Aktualisierung haftbar gemacht werden, sei es durch ihn selbst oder durch Dritte, die ihm diese Informationen zur Verf\u00fcgung stellen.<\/p>\n\n\n\n<p>Alle Angaben auf der Website dienen lediglich der Information und k\u00f6nnen ge\u00e4ndert werden. Au\u00dferdem erheben die Informationen auf der Website keinen Anspruch auf Vollst\u00e4ndigkeit. Sie werden vorbehaltlich von \u00c4nderungen gegeben, die seit ihrer Ver\u00f6ffentlichung vorgenommen wurden.<\/p>\n\n\n\n<p><strong>Artikel 4. Vertragliche Beschr\u00e4nkungen f\u00fcr technische Daten<\/strong><\/p>\n\n\n\n<p>Die Website verwendet die JavaScript-Technologie.<\/p>\n\n\n\n<p>Die Website kann nicht f\u00fcr materielle Sch\u00e4den im Zusammenhang mit der Nutzung der Website verantwortlich gemacht werden. Dar\u00fcber hinaus verpflichtet sich der Nutzer der Website, auf die Website mit aktuellen Ger\u00e4ten zuzugreifen, die keine Viren enthalten, und mit einem aktuellen Browser der neuesten Generation.<\/p>\n\n\n\n<p><strong>Artikel 5. Geistiges Eigentum und F\u00e4lschungen<\/strong><\/p>\n\n\n\n<p>Der Websiteinhaber ist der Inhaber der Rechte an geistigem Eigentum oder verf\u00fcgt \u00fcber die Nutzungsrechte an allen Elementen, die auf der Website zug\u00e4nglich sind, insbesondere an den Texten, Bildern, Grafiken, Logos, Symbolen, T\u00f6nen, Software.<\/p>\n\n\n\n<p>Jede Vervielf\u00e4ltigung, Darstellung, Modifizierung, Ver\u00f6ffentlichung, Anpassung aller oder eines Teils der Elemente der Website, unabh\u00e4ngig von den verwendeten Mitteln oder Verfahren, ist ohne die vorherige schriftliche Genehmigung des Website-Eigent\u00fcmers verboten.<\/p>\n\n\n\n<p>Jede unbefugte Nutzung der Website oder eines ihrer Elemente wird als Versto\u00df betrachtet und strafrechtlich verfolgt.<\/p>\n\n\n\n<p><strong>Artikel 6. Begrenzung der Haftung<\/strong><\/p>\n\n\n\n<p>Der Website-Betreiber kann nicht f\u00fcr direkte und indirekte Sch\u00e4den haftbar gemacht werden, die dem Ger\u00e4t des Nutzers beim Zugriff auf die Website entstehen und entweder aus der Verwendung von Ger\u00e4ten resultieren, die nicht den in Punkt 4 genannten Spezifikationen entsprechen, oder aus dem Auftreten eines Fehlers oder einer Inkompatibilit\u00e4t.<\/p>\n\n\n\n<p>Der Website-Betreiber kann nicht auch f\u00fcr Folgesch\u00e4den (wie Marktverlust oder entgangene Gewinnchancen), die sich aus der Nutzung der Website ergeben, haftbar gemacht werden.<\/p>\n\n\n\n<p>Interaktive Bereiche (M\u00f6glichkeit, im Kontaktbereich Fragen zu stellen) stehen den Nutzern zur Verf\u00fcgung. Der Website-Betreiber beh\u00e4lt sich das Recht vor, ohne vorherige Ank\u00fcndigung Inhalte, die in diesem Bereich ver\u00f6ffentlicht werden und gegen die geltenden Gesetze im Sitzland des Verk\u00e4ufers versto\u00dfen, insbesondere die datenschutzrechtlichen Bestimmungen, zu l\u00f6schen. Gegebenenfalls beh\u00e4lt sich der Website-Betreiber auch das Recht vor, die zivil- und\/oder strafrechtliche Haftung des Nutzers in Frage zu stellen, insbesondere bei rassistischen, beleidigenden, diffamierenden oder pornografischen Nachrichten, unabh\u00e4ngig vom verwendeten Medium (Text, Foto usw.).<\/p>\n\n\n\n<p><strong>Artikel 7. Verwaltung der personenbezogenen Daten<\/strong><\/p>\n\n\n\n<p>Bei der Nutzung der Website kann Folgendes erfasst werden: die URL der Links, \u00fcber die der Nutzer auf die Website zugegriffen hat, der Zugangs-Provider des Nutzers, die Internet-Protokolladresse (IP) des Nutzers.<\/p>\n\n\n\n<p>In jedem Fall sammelt der Websitebetreiber nur personenbezogene Daten, die sich auf den Nutzer beziehen, f\u00fcr den Bedarf bestimmter vom Website angebotener Dienste. Der Nutzer stellt diese Informationen in voller Kenntnis der Sachlage zur Verf\u00fcgung, insbesondere wenn er sie selbst eingibt. Es wird dann dem Nutzer der Website mitgeteilt, ob diese Informationen zu geben sind oder nicht.<\/p>\n\n\n\n<p>Gem\u00e4\u00df den Bestimmungen \u00fcber die Datenverarbeitung, die Dateien und die Freiheiten hat jeder Nutzer ein Recht auf Zugang, Berichtigung und Widerspruch zu den ihn betreffenden personenbezogenen Daten, indem er einen schriftlichen und unterzeichneten Antrag stellt, dem eine Kopie des Ausweises mit Unterschrift des Inhabers des Dokuments beigef\u00fcgt ist und in dem die Adresse angegeben ist, an die die Antwort geschickt werden muss.<\/p>\n\n\n\n<p>Keine pers\u00f6nlichen Daten des Nutzers der Website werden ohne Wissen des Nutzers ver\u00f6ffentlicht, auf irgendeinem Medium an Dritte weitergegeben, \u00fcbertragen, abgetreten oder verkauft. Nur die Annahme der \u00dcbernahme des Website-Betreibers und seiner Rechte w\u00fcrde die \u00dcbermittlung der genannten Informationen an den potenziellen K\u00e4ufer zulassen, der seinerseits an die gleiche Verpflichtung gebunden w\u00e4re, Daten in Bezug auf den Nutzer der Website zu speichern und zu \u00e4ndern.<\/p>\n\n\n\n<p>Die Datenbanken sind durch die Bestimmungen \u00fcber den rechtlichen Schutz von Datenbanken gesch\u00fctzt.<\/p>\n\n\n\n<p><strong>Artikel 8. Hypertext-Links und Cookies<\/strong><\/p>\n\n\n\n<p>Die Website enth\u00e4lt eine Reihe von Hypertext-Links zu anderen Websites, die mit der Genehmigung des Website-Betreibers eingerichtet wurden. Der Website-Betreiber hat jedoch keine M\u00f6glichkeit, den Inhalt der so besuchten Websites zu \u00fcberpr\u00fcfen und \u00fcbernimmt daher keine Verantwortung daf\u00fcr.<\/p>\n\n\n\n<p>Das Surfen auf der Website kann zur Installation von Cookies auf dem Computer des Nutzers f\u00fchren. Ein Cookie ist eine kleine Datei, die keine Identifizierung des Benutzers erm\u00f6glicht, sondern Informationen \u00fcber die Navigation eines Computers auf einer Website speichert. Die auf diese Weise gewonnenen Daten sollen die sp\u00e4tere Navigation auf der Website erleichtern und auch verschiedene Ma\u00dfnahmen zur Besucherbetreuung erm\u00f6glichen.<\/p>\n\n\n\n<p>Die Verweigerung der Installation eines Cookies kann den Zugang zu bestimmten Diensten unm\u00f6glich machen. Der Nutzer kann seinen Computer jedoch wie folgt konfigurieren, um die Installation von Cookies zu verweigern:<\/p>\n\n\n\n<p>Im Internet Explorer: Registerkarte Extras (Piktogramm in Form eines Zahnrads oben rechts) \/ Internetoptionen. Klicken Sie auf Datenschutz und w\u00e4hlen Sie Alle Cookies blockieren. Best\u00e4tigen Sie mit Ok.<\/p>\n\n\n\n<p>Unter Firefox: Klicken Sie oben im Browserfenster auf die Firefox-Schaltfl\u00e4che und gehen Sie dann auf die Registerkarte Optionen. Klicken Sie auf die Registerkarte Datenschutz. Setzen Sie die Aufbewahrungsregeln auf : Benutzerdefinierte Einstellungen f\u00fcr den Verlauf verwenden. Deaktivieren Sie schlie\u00dflich das H\u00e4kchen, um Cookies zu deaktivieren.<\/p>\n\n\n\n<p>In Safari: Klicken Sie oben rechts im Browser auf das Men\u00fcsymbol (symbolisiert durch ein Zahnrad). W\u00e4hlen Sie Einstellungen. Klicken Sie auf Erweiterte Einstellungen anzeigen. Klicken Sie im Abschnitt \"Datenschutz\" auf Inhaltseinstellungen. In der Rubrik \"Cookies\" k\u00f6nnen Sie Cookies blockieren.<\/p>\n\n\n\n<p>In Chrome: Klicken Sie oben rechts im Browser auf das Men\u00fcsymbol (symbolisiert durch drei horizontale Linien). W\u00e4hlen Sie Einstellungen. Klicken Sie auf Erweiterte Einstellungen anzeigen. Klicken Sie im Abschnitt \"Datenschutz\" auf Einstellungen. In der Registerkarte \"Datenschutz\" k\u00f6nnen Sie Cookies blockieren.<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Artikel 9. Anwendbares Recht und Zuweisung der Zust\u00e4ndigkeit<\/strong><\/p>\n\n\n\n<p>Jede Streitigkeit im Zusammenhang mit der Nutzung der Website unterliegt dem in Estland geltenden Recht. Die ausschlie\u00dfliche Zust\u00e4ndigkeit liegt bei den zust\u00e4ndigen Gerichten in Tallinn, Estland.<\/p>\n\n\n\n<p><strong>Artikel 10. Glossar<\/strong>&nbsp;<\/p>\n\n\n\n<p>Benutzer : Internetbenutzer, der sich \u00fcber die oben genannte Website verbindet.<\/p>\n\n\n\n<p>Personenbezogene Daten : Informationen, die in irgendeiner Form direkt oder indirekt die Identifizierung der nat\u00fcrlichen Personen, auf die sie sich beziehen, erm\u00f6glichen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Last updated: April 24, 2026 Article 1. Presentation of the site It is specified to users of the website the identity of the various stakeholders in the context of its realization and its follow-up : Owner : Ferber Enterprises O\u00dcAddress : Tornim\u00e4e tn 5, 10145, Tallinn, EstoniaLegal Form : Private limited companyEstonian Commercial Register Number [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_wp_page_template":["default"],"_wpml_word_count":["1292"],"_edit_lock":["1777026980:1"],"_wpml_location_migration_done":["1"],"_edit_last":["1"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_custom_page_level_css":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"site-post-title":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"ast-disable-related-posts":[""],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_elementor_edit_mode":[""],"_elementor_template_type":[""],"_elementor_data":[""],"_elementor_conditions":["a:0:{}"],"_uag_css_file_name":["uag-css-3.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:7133:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6f939b3.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-e6f939b3.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:13:{i:0;s:14:\"core\/paragraph\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:17:\"core\/latest-posts\";i:5;s:20:\"core\/latest-comments\";i:6;s:13:\"core\/archives\";i:7;s:15:\"core\/categories\";i:8;s:10:\"uagb\/image\";i:9;s:11:\"core\/spacer\";i:10;s:30:\"woocommerce\/product-categories\";i:11;s:10:\"core\/image\";i:12;s:14:\"core\/shortcode\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1777992155\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.stoprodent.com\/ch-de\/author\/admin2721\/"},"uagb_comment_info":0,"uagb_excerpt":"Last updated: April 24, 2026 Article 1. Presentation of the site It is specified to users of the website the identity of the various stakeholders in the context of its realization and its follow-up : Owner : Ferber Enterprises O\u00dcAddress : Tornim\u00e4e tn 5, 10145, Tallinn, EstoniaLegal Form : Private limited companyEstonian Commercial Register Number&hellip;","_links":{"self":[{"href":"https:\/\/www.stoprodent.com\/ch-de\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stoprodent.com\/ch-de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.stoprodent.com\/ch-de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.stoprodent.com\/ch-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stoprodent.com\/ch-de\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":3,"href":"https:\/\/www.stoprodent.com\/ch-de\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":23180,"href":"https:\/\/www.stoprodent.com\/ch-de\/wp-json\/wp\/v2\/pages\/3\/revisions\/23180"}],"wp:attachment":[{"href":"https:\/\/www.stoprodent.com\/ch-de\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}